{"id":6500,"date":"2013-05-02T10:13:20","date_gmt":"2013-05-02T08:13:20","guid":{"rendered":"http:\/\/overnighter.wp.velocontent.de\/files\/2013\/05\/ortlieb.jpg"},"modified":"2013-05-02T10:13:20","modified_gmt":"2013-05-02T08:13:20","slug":"ortlieb","status":"inherit","type":"attachment","link":"https:\/\/overnighter.de\/en\/ortlieb\/","title":{"rendered":"ortlieb"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-6500","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a8ejB5-1GQ","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/overnighter.de\/wp-content\/blogs.dir\/6\/files\/2013\/05\/ortlieb.jpg'><img decoding=\"async\" width=\"200\" height=\"58\" src=\"https:\/\/overnighter.de\/wp-content\/blogs.dir\/6\/files\/2013\/05\/ortlieb.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":200,"height":58,"file":"2013\/05\/ortlieb.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/overnighter.de\/wp-content\/blogs.dir\/6\/files\/2013\/05\/ortlieb.jpg","_links":{"self":[{"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/media\/6500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/comments?post=6500"}]}}