{"id":6499,"date":"2013-05-02T10:13:19","date_gmt":"2013-05-02T08:13:19","guid":{"rendered":"http:\/\/overnighter.wp.velocontent.de\/files\/2013\/05\/giro.jpg"},"modified":"2013-05-02T10:13:19","modified_gmt":"2013-05-02T08:13:19","slug":"giro","status":"inherit","type":"attachment","link":"https:\/\/overnighter.de\/en\/giro\/","title":{"rendered":"giro"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-6499","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a8ejB5-1GP","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/overnighter.de\/wp-content\/blogs.dir\/6\/files\/2013\/05\/giro.jpg'><img decoding=\"async\" width=\"200\" height=\"43\" src=\"https:\/\/overnighter.de\/wp-content\/blogs.dir\/6\/files\/2013\/05\/giro.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":200,"height":43,"file":"2013\/05\/giro.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/overnighter.de\/wp-content\/blogs.dir\/6\/files\/2013\/05\/giro.jpg","_links":{"self":[{"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/media\/6499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/overnighter.de\/en\/wp-json\/wp\/v2\/comments?post=6499"}]}}